{"id":3618,"date":"2025-10-01T16:08:50","date_gmt":"2025-10-01T14:08:50","guid":{"rendered":"http:\/\/www.theaterzirkus-dresden.de\/?post_type=tribe_events&#038;p=3618"},"modified":"2025-10-01T16:08:50","modified_gmt":"2025-10-01T14:08:50","slug":"a-christmas-carol-8","status":"publish","type":"tribe_events","link":"https:\/\/www.theaterzirkus-dresden.de\/en\/dates\/a-christmas-carol-8\/","title":{"rendered":"A CHRISTMAS CAROL"},"content":{"rendered":"<p>Weihnachtstheater auf Schloss Scharfenberg inklusive 3-G\u00e4nge-Buffet<\/p>\n<p>Das Jahr neigt sich dem Ende zu. Zeit mit Familie, Kollegen und Freunden die Weihnachtszeit zu feiern.<\/p>\n<p>Wenn die Schatten des Abends niedersinken und der Wintersturm eisige Winde durch die linkselbischen T\u00e4ler fegt, funkelt das Kerzenlicht, und w\u00e4rmend knistert das Holz im Kamin. Jetzt ist es an der Zeit, in den fast tausendj\u00e4hrigen Mauern des Schlosses Scharfenberg Charles Dickens Weihnachtsgeschichte zu lauschen.<\/p>\n<p>Am Heiligabend im viktorianischen London schl\u00e4gt der geizige und hartherzige Geldverleiher Ebenezer Scrooge die Einladung zum Weihnachtsessen bei seinem Neffen wie jedes Jahr aus, behandelt seinen Angestellten schlecht und verwehrt dem Waisenhaus die Spende. In seiner einsamen Welt hat schon lange das Geld \u00fcber die Menschlichkeit gesiegt.<\/p>\n<p>Punkt Mitternacht, mit Beginn der Geisterstunde erh\u00e4lt er jedoch unerwarteten und schauerlichen Besuch vom Geist seines verstorbenen Gesch\u00e4ftspartners Jacob Marley, der aufgrund seiner Habgier und Selbstsucht dazu verdammt ist, ewig als kettenbeladener, geschundener Geist die Welt zu durchstreifen. Er warnt Scrooge vor einem \u00e4hnlichen Schicksal und k\u00fcndigt ihm drei weitere Besuche aus dem Jenseits an. Nacheinander wird er von den Geistern der vergangenen, der gegenw\u00e4rtigen und der zuk\u00fcnftigen Weihnacht heimgesucht. Eindringlich zeigen sie ihm, wie viel Gl\u00fcck er durch seine Gef\u00fchllosigkeit und seinen Zynismus bisher vers\u00e4umt und wie viel Ungl\u00fcck er in das Leben anderer Menschen gebracht hat. Sie f\u00fchren ihm die Einsamkeit vor, in der er einmal sterben wird, falls er sein Leben nicht \u00e4ndert.<\/p>\n<p>Schaffen es die n\u00e4chtlichen Gestalten, das Herz des alten Griesgrams zu erw\u00e4rmen? Und wird Ebenezer Scrooge doch noch Weihnachten feiern?<\/p>\n<p>Seit fast zwei Jahrhunderten begeistert diese Geschichte Menschen aller Generationen auf der ganzen Welt und erw\u00e4rmt jedes Herz mit seiner inspirierenden Botschaft.<\/p>\n<p>Thomas F\u00f6rster wird als Ebenezer Scrooge zu erleben sein, w\u00e4hrenddessen Tom Quaas, bekannt f\u00fcr seine virtuose Wandelbarkeit, s\u00e4mtliche andere Rollen der Geschichte spielt. Die Dritte im Bunde ist die Konzertpianistin Mirjana Raji\u0107.<\/p>\n<p>Neben Schauspielkunst und wunderbarer Musik spielen die Atmosph\u00e4re des Schlosses und theatrale Mittel wie Projektionen, H\u00f6r- und Schattenspiel eine besondere Rolle in dieser Inszenierung.<\/p>\n<p>ES SPIELEN UND MUSIZIEREN<\/p>\n<p>THOMAS F\u00d6RSTER Ebenezer Scrooge<br \/>\nTOM QUAAS Bob Cratchit | Geist von Jacob Marley | Geist der vergangenen, der gegenw\u00e4rtigen und zuk\u00fcnftigen Weihnacht | weitere Figuren<br \/>\nMIRJANA RAJI\u0106 am Fl\u00fcgel<\/p>\n<p>MATTHIAS NAGATIS Regie<br \/>\nTHOMAS F\u00d6RSTER St\u00fcckfassung<\/p>\n<p>Dieser Abend wird veranstaltet durch die Theater Mei\u00dfen gGmbH in Kooperation mit dem Kulturkreis Schloss Scharfenberg e.V.<\/p>\n<p>VERANSTALTUNGSORT<br \/>\nSchloss Scharfenberg<br \/>\nSchlo\u00dfweg 1, 01665 Klipphausen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weihnachtstheater auf Schloss Scharfenberg inklusive 3-G\u00e4nge-Buffet Das Jahr neigt sich dem Ende zu. Zeit mit Familie, Kollegen und Freunden die Weihnachtszeit zu feiern. Wenn die Schatten des Abends niedersinken und&#8230;<\/p>\n<p><a href=\"https:\/\/www.theaterzirkus-dresden.de\/en\/dates\/a-christmas-carol-8\/\"><span class=\"glyphicon glyphicon-arrow-right\"><\/span>&nbsp;Continue reading<\/a><\/p>","protected":false},"author":3,"featured_media":3593,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3618","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tribe_events\/3618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tribe_events\/3618\/revisions"}],"predecessor-version":[{"id":3622,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tribe_events\/3618\/revisions\/3622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/media\/3593"}],"wp:attachment":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/media?parent=3618"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tags?post=3618"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=3618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}