{"id":339,"date":"2015-05-20T16:22:12","date_gmt":"2015-05-20T15:22:12","guid":{"rendered":"http:\/\/www.theaterzirkus-dresden.de\/?p=339"},"modified":"2015-05-20T16:24:35","modified_gmt":"2015-05-20T15:24:35","slug":"unter-dem-milchwald-von-dylan-thomas","status":"publish","type":"post","link":"https:\/\/www.theaterzirkus-dresden.de\/en\/unter-dem-milchwald-von-dylan-thomas\/","title":{"rendered":"UNTER DEM MILCHWALD von Dylan Thomas"},"content":{"rendered":"<p>mit Anna B\u00f6hm und <a title=\"Theater &amp; B\u00fchne\" href=\"http:\/\/www.theaterzirkus-dresden.de\/direktor\/auf-der-buehne\/\">Tom Quass<\/a> am Freitag, 22. Mai 2015 um 20 Uhr auf Schloss Batzdorf<\/p>\n<p><a href=\"http:\/\/www.batzdorfer-schloss.de\/kartenreservierung\/\">Kartenreservierung<\/a><\/p>\n<p><!--more-->Das ber\u00fchmteste H\u00f6rbuch der Rundfunkgeschichte ist angef\u00fcllt mit stimmlichen Experimenten, sinnlichen Metaphern und Ger\u00e4uschen eines Tages im walisischen Fischerdorf Llarregyb. Im Mittelpunkt stehen eine Vielzahl von Charakteren, deren Hoffnungen und Tr\u00e4ume sich dem Publikum in einer schnellen Abfolge heiterer und lyrischer Dialoge entfalten. Da ist zum Beispiel Captain Cat, ein blinder ehemaliger Seekapit\u00e4n, der von seinen toten Seekameraden tr\u00e4umt. Die Schneiderin Myfanwy Price tr\u00e4umt davon, den Tuchh\u00e4ndler Mog Edwards zu heiraten, der ihre Gef\u00fchle erwidert, sich ihr aber nur in Briefen n\u00e4hern darf. Die Pensionswirtin Mrs. Ogmore-Pritchard ist eine mehrfache Witwe, die von ihren verstorbenen M\u00e4nnern tr\u00e4umt und sich weigert, G\u00e4ste aufzunehmen, weil die Lebenden das Haus schmutzig machen k\u00f6nnten\u2026<\/p>\n<p>Tom Quaas liest und spielt die \u00fcber 30 Figuren an diesem Abend selbst und wird von Anna B\u00f6hm musikalisch begleitet.<\/p>\n<p>Die DNN schrieb zur Premiere der szenischen Lesung \u201cUnter dem Milchwald\u201d bei den Pfingstfestspielen auf Schloss Batzdorf: <em>\u201cDie Intensit\u00e4t des Spiels ist wie ein Sog, \u00fcberbordend mengen sich Komik und Bitterkeit und ungeachtet dessen, dass einer Premiere die Routine fehlen muss, ist hier etwas gro\u00dfartig Poetisches gelungen, dem man viele Zuschauer w\u00fcnscht.\u201d<\/em>\u00a0 (Mai 2010)<\/p>\n<p>22. Mai 2015 UNTER DEM MILCHWALD, Beginn: 20 Uhr anl\u00e4sslich der <a title=\"18. Pfingstfestspiele Schloss Batzdorf\" href=\"http:\/\/www.theaterzirkus-dresden.de\/18-pfingstfestspiele-schloss-batzdorf-3\/\">18. Pfingstfestspiele<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>mit Anna B\u00f6hm und Tom Quass am Freitag, 22. Mai 2015 um 20 Uhr auf Schloss Batzdorf Kartenreservierung<\/p>\n<p><a href=\"https:\/\/www.theaterzirkus-dresden.de\/en\/unter-dem-milchwald-von-dylan-thomas\/\"><span class=\"glyphicon glyphicon-arrow-right\"><\/span>&nbsp;Continue reading<\/a><\/p>","protected":false},"author":3,"featured_media":338,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":4,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":343,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/posts\/339\/revisions\/343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/media\/338"}],"wp:attachment":[{"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theaterzirkus-dresden.de\/en\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}